{"id":4185,"date":"2023-01-24T18:11:25","date_gmt":"2023-01-24T18:11:25","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/ruysdael-piccadilly\/"},"modified":"2026-05-15T20:22:36","modified_gmt":"2026-05-15T18:22:36","slug":"ruysdael-piccadilly","status":"publish","type":"product","link":"https:\/\/mail.ton.connectingminds.net\/pt\/retro-wielershirt\/ruysdael-piccadilly\/","title":{"rendered":"CAMISA DE CICLISMO RUYSDAEL (a)-PICCADILLY-DE KRUIK 1977"},"content":{"rendered":"<p>RUYSDAEL-PICCADILLY-DE KRUIK 1977<\/p>","protected":false},"excerpt":{"rendered":"<p>RUYSDAEL-PICCADILLY-DE KRUIK 1977<\/p>","protected":false},"featured_media":187213,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-4185","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RUYSDAEL (a)-PICCADILLY-DE KRUIK  1977   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RUYSDAEL (a)-PICCADILLY-DE KRUIK  1977   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"RUYSDAEL-PICCADILLY-DE KRUIK 1977\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T18:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_20260515_194157-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/\",\"name\":\"RUYSDAEL (a)-PICCADILLY-DE KRUIK 1977 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_20260515_194157-scaled.jpg\",\"datePublished\":\"2023-01-24T18:11:25+00:00\",\"dateModified\":\"2026-05-15T18:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_20260515_194157-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_20260515_194157-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"RUYSDAEL-PICCADILLY-DE KRUIK 1977\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-radtrikot\\\/ruysdael-piccadilly\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RUYSDAEL (a)-PICCADILLY-DE KRUIK 1977 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.ton.connectingminds.net\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RUYSDAEL (a)-PICCADILLY-DE KRUIK 1977 CAMISA DE CICLISMO - Ton Merckx Cycling Jerseys - Tour pelo mundo das camisas de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/","og_locale":"pt_PT","og_type":"article","og_title":"RUYSDAEL (a)-PICCADILLY-DE KRUIK  1977   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"RUYSDAEL-PICCADILLY-DE KRUIK 1977","og_url":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-15T18:22:36+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_20260515_194157-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/","url":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/","name":"RUYSDAEL (a)-PICCADILLY-DE KRUIK 1977 CAMISA DE CICLISMO - Ton Merckx Cycling Jerseys - Tour pelo mundo das camisas de ciclismo","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/IMG_20260515_194157-scaled.jpg","datePublished":"2023-01-24T18:11:25+00:00","dateModified":"2026-05-15T18:22:36+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/#primaryimage","url":"https:\/\/mail.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/IMG_20260515_194157-scaled.jpg","contentUrl":"https:\/\/mail.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/IMG_20260515_194157-scaled.jpg","width":1920,"height":2560,"caption":"RUYSDAEL-PICCADILLY-DE KRUIK 1977"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-radtrikot\/ruysdael-piccadilly\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"RUYSDAEL (a)-PICCADILLY-DE KRUIK 1977 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.ton.connectingminds.net\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.ton.connectingminds.net\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/product\/4185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/media\/187213"}],"wp:attachment":[{"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/media?parent=4185"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/product_brand?post=4185"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/product_cat?post=4185"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.ton.connectingminds.net\/pt\/wp-json\/wp\/v2\/product_tag?post=4185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}